{"id":15225,"date":"2025-03-07T14:21:55","date_gmt":"2025-03-07T14:21:55","guid":{"rendered":"https:\/\/tjekvik.com\/kundenberichte\/fallstudie-halliwell-jones\/"},"modified":"2025-03-17T15:51:05","modified_gmt":"2025-03-17T15:51:05","slug":"fallstudie-halliwell-jones","status":"publish","type":"page","link":"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/","title":{"rendered":"Fallstudie Halliwell Jones"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"15225\" class=\"elementor elementor-15225 elementor-13899\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56add967 e-flex e-con-boxed e-con e-parent\" data-id=\"56add967\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-617ba7db e-con-full e-flex e-con e-child\" data-id=\"617ba7db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e21dd65 elementor-widget elementor-widget-image\" data-id=\"2e21dd65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.halliwelljones.co.uk\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"100\" src=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/halliwell-jones-logo.webp\" class=\"attachment-medium size-medium wp-image-13903\" alt=\"Haliwell Jones logo\" title=\"halliwell-jones-logo | Tjekvik\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e37b3d7 e-con-full elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-mobile_extra e-flex e-con e-child\" data-id=\"3e37b3d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49b7969b elementor-widget elementor-widget-image\" data-id=\"49b7969b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/New-Reception-Area-Warrington--768x1024.webp\" class=\"attachment-medium_large size-medium_large wp-image-13909\" alt=\"Haliwell Jones reception\" srcset=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/New-Reception-Area-Warrington--768x1024.webp 768w, https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/New-Reception-Area-Warrington--225x300.webp 225w, https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/New-Reception-Area-Warrington-.webp 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"New Reception Area Warrington | Tjekvik\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-963b28e elementor-widget elementor-widget-heading\" data-id=\"963b28e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Halliwell Jones hat seine gr\u00f6\u00dfte Herausforderung '\u00fcber Nacht' gel\u00f6st<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3aa0e3df e-con-full e-flex e-con e-child\" data-id=\"3aa0e3df\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70b8be50 elementor-widget elementor-widget-text-editor\" data-id=\"70b8be50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Juli 30, 2021<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b6a81bf elementor-widget elementor-widget-text-editor\" data-id=\"7b6a81bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"row-fluid-wrapper row-depth-1 row-number-1 dnd_area-row-0-max-width-section-centering dnd_area-row-0-vertical-alignment dnd_area-row-0-background-layers dnd-section dnd_area-row-0-padding dnd_area-row-0-background-image\">\n<div class=\"row-fluid \">\n<div class=\"span12 widget-span widget-type-cell dnd-column dnd_area-column-1-vertical-alignment\" data-widget-type=\"cell\" data-x=\"0\" data-w=\"12\">\n<div class=\"row-fluid-wrapper row-depth-1 row-number-3 dnd_area-column-1-row-1-vertical-alignment dnd-row\">\n<div class=\"row-fluid \">\n<div class=\"span6 widget-span widget-type-cell dnd_area-column-4-vertical-alignment dnd-column\" data-widget-type=\"cell\" data-x=\"6\" data-w=\"6\">\n<div class=\"row-fluid-wrapper row-depth-1 row-number-4 dnd_area-column-4-row-0-padding dnd-row\">\n<div class=\"row-fluid \">\n<div class=\"span12 widget-span widget-type-custom_widget dnd-module\" data-widget-type=\"custom_widget\" data-x=\"0\" data-w=\"12\">\n<div id=\"hs_cos_wrapper_dnd_area-module-5\" class=\"hs_cos_wrapper hs_cos_wrapper_widget hs_cos_wrapper_type_module widget-type-rich_text widget-type-rich_text\" data-hs-cos-general-type=\"widget\" data-hs-cos-type=\"module\">\n<p>Der erste Kunde von Tjekvik in Gro\u00dfbritannien, Halliwell Jones, l\u00f6ste seine gr\u00f6\u00dfte Herausforderung &#8222;\u00fcber Nacht&#8220;, so der Aftersales Manager der Gruppe, Lincoln Delve.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24ca301f e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"24ca301f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56ab42a2 elementor-widget elementor-widget-image\" data-id=\"56ab42a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/New-Reception-Area-Warrington--768x1024.webp\" class=\"attachment-medium_large size-medium_large wp-image-13909\" alt=\"Haliwell Jones reception\" srcset=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/New-Reception-Area-Warrington--768x1024.webp 768w, https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/New-Reception-Area-Warrington--225x300.webp 225w, https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/New-Reception-Area-Warrington-.webp 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"New Reception Area Warrington | Tjekvik\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f3e5a02 e-flex e-con-boxed e-con e-parent\" data-id=\"6f3e5a02\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-14466e37 e-con-full e-flex e-con e-child\" data-id=\"14466e37\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28edb2e1 elementor-widget elementor-widget-image\" data-id=\"28edb2e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/HJ-Chester-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-13915\" alt=\"Tjekvik terminal at Haliwell Jones Chester\" srcset=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/HJ-Chester-768x576.webp 768w, https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/HJ-Chester-300x225.webp 300w, https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/HJ-Chester-1024x768.webp 1024w, https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/HJ-Chester-1536x1152.webp 1536w, https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/HJ-Chester.webp 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"HJ Chester | Tjekvik\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f7ba4e9 e-con-full e-flex e-con e-child\" data-id=\"7f7ba4e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ba39a39 elementor-widget elementor-widget-text-editor\" data-id=\"2ba39a39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"span6 widget-span widget-type-custom_widget dnd_area-module-8-vertical-alignment dnd-module\" data-widget-type=\"custom_widget\" data-x=\"0\" data-w=\"6\">\n<div id=\"hs_cos_wrapper_dnd_area-module-8\" class=\"hs_cos_wrapper hs_cos_wrapper_widget hs_cos_wrapper_type_module widget-type-rich_text widget-type-rich_text\" data-hs-cos-general-type=\"widget\" data-hs-cos-type=\"module\">\n<p>Seit Jahren ist das gr\u00f6\u00dfte Problem der Gruppe von 11 BMW- und MINI-H\u00e4ndlern im Nordwesten Englands und in Nordwales &#8211; \u00e4hnlich wie bei vielen anderen H\u00e4ndlern &#8211; die Verk\u00fcrzung der Zeit, die Kunden auf einen Serviceberater warten m\u00fcssen.<\/p>\n<p>Die Einf\u00fchrung der digitalen Service-Empfangssoftware und der Premium-Kioske von Tjekvik an allen 11 Standorten der Gruppe hat die Wartezeiten erheblich verk\u00fcrzt und den Mitarbeitern des Autohauses mehr Zeit verschafft, wodurch sie ihre Produktivit\u00e4t steigern konnten.<\/p>\n<p>Laut Lincoln hat die Implementierung der Tjekvik Software und Hardware sofort Wirkung gezeigt.<\/p>\n<p>&#8222;Wir waren zu diesem Zeitpunkt nicht wirklich auf der Suche nach einer L\u00f6sung, aber wir wussten, dass BMW einige Anbieter untersuchte, und nachdem wir die Vorf\u00fchrung erlebt hatten, waren wir begeistert&#8220;, sagte er. &#8222;Unser Gesch\u00e4ftsf\u00fchrer, Philip Jones, kam an einem der Kioske vorbei und konnte ihn innerhalb von Sekunden und ohne Anleitung bedienen. <\/p>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1344aa5d e-flex e-con-boxed e-con e-parent\" data-id=\"1344aa5d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c04d8a e-con-full e-flex e-con e-child\" data-id=\"3c04d8a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4dac83ce elementor-widget elementor-widget-heading\" data-id=\"4dac83ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eine flexible Check-in-L\u00f6sung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfe3e50 elementor-widget elementor-widget-text-editor\" data-id=\"cfe3e50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"row-fluid-wrapper row-depth-1 row-number-7 dnd_area-row-2-background-layers dnd_area-row-2-padding dnd_area-row-2-background-color dnd_area-row-2-max-width-section-centering dnd-section dnd_area-row-2-vertical-alignment\">\n<div class=\"row-fluid \">\n<div class=\"span12 widget-span widget-type-cell dnd_area-column-10-vertical-alignment dnd-column\" data-widget-type=\"cell\" data-x=\"0\" data-w=\"12\">\n<div class=\"row-fluid-wrapper row-depth-1 row-number-8 dnd_area-column-10-row-0-vertical-alignment dnd-row\">\n<div class=\"row-fluid \">\n<div class=\"span12 widget-span widget-type-custom_widget dnd_area-module-12-vertical-alignment dnd-module\" data-widget-type=\"custom_widget\" data-x=\"0\" data-w=\"12\">\n<div id=\"hs_cos_wrapper_dnd_area-module-12\" class=\"hs_cos_wrapper hs_cos_wrapper_widget hs_cos_wrapper_type_module widget-type-rich_text widget-type-rich_text\" data-hs-cos-general-type=\"widget\" data-hs-cos-type=\"module\">\n<p>Das innovative System von Tjekvik erm\u00f6glicht es Kunden, ihr Fahrzeug f\u00fcr Service- und Wartungsarbeiten von zu Hause aus auf ihren eigenen Ger\u00e4ten oder \u00fcber Check-in-Kioske im Autohaus einzuchecken. Dadurch wird die Wartezeit f\u00fcr den Kunden minimiert, die Kundenzufriedenheit erh\u00f6ht und die Effizienz der Mitarbeiter des Autohauses verbessert, die ihre Zeit, die sie normalerweise f\u00fcr die Kundenbetreuung aufwenden, f\u00fcr andere Aufgaben nutzen k\u00f6nnen. <\/p>\n<p>sagte Lincoln: &#8222;Die gr\u00f6\u00dfte Herausforderung f\u00fcr uns als Unternehmen war die Zeit. Die Kunden haben keine Zeit oder wollen nicht warten, um mit einem Serviceberater zu sprechen. Wir hatten morgens lange Warteschlangen mit Leuten, die auf einen Berater warteten, und wir haben das \u00fcber Nacht behoben. Wir waren sofort in der Lage, Kundentermine zu vereinbaren und unseren Kunden eine L\u00f6sung zu bieten, mit der sie ihre Bestellung sicher aufgeben konnten.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b375c3e e-grid e-con-full e-con e-child\" data-id=\"b375c3e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4eed5b elementor-widget elementor-widget-image\" data-id=\"e4eed5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"436\" src=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/haliwell-CS-768x436.webp\" class=\"attachment-medium_large size-medium_large wp-image-13921\" alt=\"Haliwell Jones foyer before and after\" srcset=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/haliwell-CS-768x436.webp 768w, https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/haliwell-CS-300x170.webp 300w, https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/haliwell-CS-1024x582.webp 1024w, https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/03\/haliwell-CS.webp 1297w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"haliwell CS | Tjekvik\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-727e3ffe elementor-widget elementor-widget-text-editor\" data-id=\"727e3ffe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"row-fluid-wrapper row-depth-1 row-number-7 dnd_area-row-2-background-layers dnd_area-row-2-padding dnd_area-row-2-background-color dnd_area-row-2-max-width-section-centering dnd-section dnd_area-row-2-vertical-alignment\">\n<div class=\"row-fluid \">\n<div class=\"span12 widget-span widget-type-cell dnd_area-column-10-vertical-alignment dnd-column\" data-widget-type=\"cell\" data-x=\"0\" data-w=\"12\">\n<div class=\"row-fluid-wrapper row-depth-1 row-number-8 dnd_area-column-10-row-0-vertical-alignment dnd-row\">\n<div class=\"row-fluid \">\n<div class=\"span12 widget-span widget-type-custom_widget dnd_area-module-12-vertical-alignment dnd-module\" data-widget-type=\"custom_widget\" data-x=\"0\" data-w=\"12\">\n<div id=\"hs_cos_wrapper_dnd_area-module-12\" class=\"hs_cos_wrapper hs_cos_wrapper_widget hs_cos_wrapper_type_module widget-type-rich_text widget-type-rich_text\" data-hs-cos-general-type=\"widget\" data-hs-cos-type=\"module\">\n<p>Lincoln r\u00e4umt ein, dass die neue Technologie nicht jedermanns Sache ist, dass aber die Akzeptanz sowohl bei den Mitarbeitern der H\u00e4ndler als auch bei den Kunden stetig zugenommen hat. &#8222;Anfangs waren nicht alle Mitarbeiter des H\u00e4ndlers von dem System begeistert, aber als sie die Vorteile erkannten, haben sie sich gesteigert und mit der Software gearbeitet&#8220;, sagt er. <\/p>\n<p>&#8222;F\u00fcr die Kunden ist das System ein wenig &#8218;Marmite&#8216; &#8211; einige lieben es und andere wollen immer noch mit einem Menschen sprechen. Das ist auch gut so, denn wir haben jetzt mehr Zeit f\u00fcr diejenigen, die diesen Weg gehen wollen.&#8220;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6bc8659d e-flex e-con-boxed e-con e-parent\" data-id=\"6bc8659d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-52564571 e-con-full e-flex e-con e-child\" data-id=\"52564571\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58970bc elementor-widget elementor-widget-heading\" data-id=\"58970bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hohe Akzeptanz und zus\u00e4tzliche Einnahmen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dba8bf elementor-widget elementor-widget-text-editor\" data-id=\"7dba8bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"row-fluid-wrapper row-depth-1 row-number-14 cell_16769902467822-row-0-vertical-alignment dnd-row\">\n<div class=\"row-fluid \">\n<div class=\"span12 widget-span widget-type-custom_widget module_16769902467825-vertical-alignment dnd-module\" data-widget-type=\"custom_widget\" data-x=\"0\" data-w=\"12\">\n<div id=\"hs_cos_wrapper_module_16769902467825\" class=\"hs_cos_wrapper hs_cos_wrapper_widget hs_cos_wrapper_type_module widget-type-rich_text widget-type-rich_text\" data-hs-cos-general-type=\"widget\" data-hs-cos-type=\"module\">\n<p>Seit Beginn der Partnerschaft zwischen Tjekvik und Halliwell Jones im Jahr 2019 zeigen die vom System erfassten Daten klare und greifbare Vorteile f\u00fcr den Konzern.<\/p>\n<p>Allein im Jahr 2021 erzielte der Konzern \u00fcber die Tjekvik-Kioske einen Mehrwertumsatz von 67.908 \u00a3 und nahm 1.088 zus\u00e4tzliche Anfragen f\u00fcr Servicepl\u00e4ne entgegen. Im Durchschnitt nutzte ein Drittel (32%) der Kunden die Home-Check-in-Funktion, um ihre Fahrzeuge aus der Ferne anzumelden, obwohl Lincoln berichtet, dass dieser Anteil zeitweise auf bis zu 50% anstieg. <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"row-fluid-wrapper row-depth-1 row-number-15 cell_16769902467822-row-1-vertical-alignment dnd-row\">\n<div class=\"row-fluid \">\n<div class=\"span6 widget-span widget-type-cell cell_1676992060448-vertical-alignment dnd-column\" data-widget-type=\"cell\" data-x=\"0\" data-w=\"6\">\n<div class=\"row-fluid-wrapper row-depth-1 row-number-16 cell_1676992060448-row-0-vertical-alignment dnd-row\">\n<div class=\"row-fluid \">\n<div class=\"span12 widget-span widget-type-custom_widget module_16769918695412-vertical-alignment dnd-module\" data-widget-type=\"custom_widget\" data-x=\"0\" data-w=\"12\">\n<div id=\"hs_cos_wrapper_module_16769918695412\" class=\"hs_cos_wrapper hs_cos_wrapper_widget hs_cos_wrapper_type_module widget-type-rich_text widget-type-rich_text\" data-hs-cos-general-type=\"widget\" data-hs-cos-type=\"module\">\n<p>In der Zwischenzeit nutzte fast die H\u00e4lfte (45%) der Kunden den Premium-Kiosk Tjekvik, um vor Ort einzuchecken, und die Nutzung der Check-out-Funktion lag auf dem H\u00f6hepunkt der Pandemie bei 20%.<\/p>\n<p>Die Halliwell Jones Group berichtet, dass die gr\u00f6\u00dften Vorteile der Zusammenarbeit mit Tjekvik bei der Bereitstellung eines digitalen Service-Empfangs die Auswirkungen auf die Kundenzufriedenheit durch die Verringerung der Warteschlangen und die Steigerung des Gesch\u00e4ftsergebnisses um fast 70.000 \u00a3 in den letzten 12 Monaten waren. In Verbindung mit der reibungslosen Zusammenarbeit mit Tjekvik hat dies zu einem schmerzfreien und profitablen Prozess gef\u00fchrt. <\/p>\n<p>Mit Blick auf die Zukunft sagte Lincoln, dass weitere Integrationen die Vorteile von Tjekvik f\u00fcr Halliwell Jones nur verst\u00e4rken w\u00fcrden: &#8222;Mehr Interaktion mit unserem Keyloop Drive DMS w\u00e4re zu begr\u00fc\u00dfen, ebenso wie die Verwendung von Videobildern. Und wenn wir unser System mit der Nummernschilderkennung (NPR) verbinden k\u00f6nnten, w\u00fcrde ich mir w\u00fcnschen, dass die Maschine dies erkennt und den Kunden mit seinem Namen begr\u00fc\u00dft, wenn er sich dem Kiosk n\u00e4hert.&#8220;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72e37382 e-grid e-con-boxed e-con e-parent\" data-id=\"72e37382\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8480b2f elementor-widget elementor-widget-counter\" data-id=\"8480b2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">In zus\u00e4tzlichen Einnahmen<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">\u00a3<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"70000\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32ba7c1b elementor-widget elementor-widget-counter\" data-id=\"32ba7c1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Check-in von zu Hause<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"32\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">%<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ae50604 elementor-widget elementor-widget-counter\" data-id=\"5ae50604\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Terminals Ckeck-in<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"45\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">%<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfdcd74 e-flex e-con-boxed e-con e-parent\" data-id=\"cfdcd74\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9274cfc elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"9274cfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\"Wir hatten morgens lange Warteschlangen mit Leuten, die auf einen Berater warteten, und wir haben das \u00fcber Nacht behoben. Wir waren sofort in der Lage, Kundentermine zu erstellen und den Kunden eine L\u00f6sung zu bieten, mit der sie sicher einen Termin vereinbaren k\u00f6nnen.\"<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Lincoln Delve<\/span><span class=\"elementor-testimonial__title\">Aftersales Manager der Gruppe, Halliwell Jones<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Halliwell Jones hat seine gr\u00f6\u00dfte Herausforderung &#8218;\u00fcber Nacht&#8216; gel\u00f6st Juli 30, 2021 Der erste Kunde von Tjekvik in Gro\u00dfbritannien, Halliwell Jones, l\u00f6ste seine gr\u00f6\u00dfte Herausforderung &#8222;\u00fcber Nacht&#8220;, so der Aftersales Manager der Gruppe, Lincoln Delve. Seit Jahren ist das gr\u00f6\u00dfte Problem der Gruppe von 11 BMW- und MINI-H\u00e4ndlern im Nordwesten Englands und in Nordwales &#8211; [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"parent":3777,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_angie_page":false,"footnotes":""},"class_list":["post-15225","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lesen Sie die Fallstudie von Halliwell Jones, um zu erfahren, wie die Einf\u00fchrung der digitalen Service-Kioske von Tjekvik die Wartezeit verk\u00fcrzt und die Produktivit\u00e4t des Autohauses erh\u00f6ht hat.\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"google-site-verification\" content=\"9PXm2QtMM5RDVYRpa-EGrnVOmNWMB8RJJfHjriN0nJQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Tjekvik | Self-Service Solutions for Dealerships\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Tjekvik | Fallstudie Halliwell Jones\" \/>\n\t\t<meta property=\"og:description\" content=\"Lesen Sie die Fallstudie von Halliwell Jones, um zu erfahren, wie die Einf\u00fchrung der digitalen Service-Kioske von Tjekvik die Wartezeit verk\u00fcrzt und die Produktivit\u00e4t des Autohauses erh\u00f6ht hat.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/02\/NK28037-Edit1-e1739453183974.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/02\/NK28037-Edit1-e1739453183974.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1158\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-03-07T14:21:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-03-17T15:51:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TjekvikAutoinnovationAps\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Tjekvik | Fallstudie Halliwell Jones\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lesen Sie die Fallstudie von Halliwell Jones, um zu erfahren, wie die Einf\u00fchrung der digitalen Service-Kioske von Tjekvik die Wartezeit verk\u00fcrzt und die Produktivit\u00e4t des Autohauses erh\u00f6ht hat.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/02\/NK28037-Edit1-e1739453183974.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/kundenberichte\\\/fallstudie-halliwell-jones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/#listItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/kundenberichte\\\/#listItem\",\"name\":\"Kundenberichte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"#listItem\",\"name\":\"Tjekvik\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/kundenberichte\\\/#listItem\",\"position\":3,\"name\":\"Kundenberichte\",\"item\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/kundenberichte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/kundenberichte\\\/fallstudie-halliwell-jones\\\/#listItem\",\"name\":\"Fallstudie Halliwell Jones\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/kundenberichte\\\/fallstudie-halliwell-jones\\\/#listItem\",\"position\":4,\"name\":\"Fallstudie Halliwell Jones\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/kundenberichte\\\/#listItem\",\"name\":\"Kundenberichte\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/#organization\",\"name\":\"Tjekvik\",\"description\":\"Self-Service Solutions for Dealerships\",\"url\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/\",\"telephone\":\"+447470214847\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/tjekvik.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/TJEKVIK_Brandmark_RGB.png\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/kundenberichte\\\/fallstudie-halliwell-jones\\\/#organizationLogo\",\"width\":473,\"height\":473,\"caption\":\"Tjekvik brand icon\"},\"image\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/kundenberichte\\\/fallstudie-halliwell-jones\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/@tjekvik\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tjekvik\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/kundenberichte\\\/fallstudie-halliwell-jones\\\/#webpage\",\"url\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/kundenberichte\\\/fallstudie-halliwell-jones\\\/\",\"name\":\"Tjekvik | Fallstudie Halliwell Jones\",\"description\":\"Lesen Sie die Fallstudie von Halliwell Jones, um zu erfahren, wie die Einf\\u00fchrung der digitalen Service-Kioske von Tjekvik die Wartezeit verk\\u00fcrzt und die Produktivit\\u00e4t des Autohauses erh\\u00f6ht hat.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/kundenberichte\\\/fallstudie-halliwell-jones\\\/#breadcrumblist\"},\"datePublished\":\"2025-03-07T14:21:55+00:00\",\"dateModified\":\"2025-03-17T15:51:05+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/\",\"name\":\"Tjekvik\",\"description\":\"Self-Service Solutions for Dealerships\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Tjekvik | Fallstudie Halliwell Jones<\/title>\n\n","aioseo_head_json":{"title":"Tjekvik | Fallstudie Halliwell Jones","description":"Lesen Sie die Fallstudie von Halliwell Jones, um zu erfahren, wie die Einf\u00fchrung der digitalen Service-Kioske von Tjekvik die Wartezeit verk\u00fcrzt und die Produktivit\u00e4t des Autohauses erh\u00f6ht hat.","canonical_url":"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"google-site-verification":"9PXm2QtMM5RDVYRpa-EGrnVOmNWMB8RJJfHjriN0nJQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/#listItem","position":2,"name":"Home","item":"https:\/\/tjekvik.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/kundenberichte\/#listItem","name":"Kundenberichte"},"previousItem":{"@type":"ListItem","@id":"#listItem","name":"Tjekvik"}},{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/kundenberichte\/#listItem","position":3,"name":"Kundenberichte","item":"https:\/\/tjekvik.com\/de\/kundenberichte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/#listItem","name":"Fallstudie Halliwell Jones"},"previousItem":{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/#listItem","position":4,"name":"Fallstudie Halliwell Jones","previousItem":{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/kundenberichte\/#listItem","name":"Kundenberichte"}}]},{"@type":"Organization","@id":"https:\/\/tjekvik.com\/de\/#organization","name":"Tjekvik","description":"Self-Service Solutions for Dealerships","url":"https:\/\/tjekvik.com\/de\/","telephone":"+447470214847","logo":{"@type":"ImageObject","url":"https:\/\/tjekvik.com\/wp-content\/uploads\/2023\/05\/TJEKVIK_Brandmark_RGB.png","@id":"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/#organizationLogo","width":473,"height":473,"caption":"Tjekvik brand icon"},"image":{"@id":"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/#organizationLogo"},"sameAs":["https:\/\/www.youtube.com\/@tjekvik","https:\/\/www.linkedin.com\/company\/tjekvik\/"]},{"@type":"WebPage","@id":"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/#webpage","url":"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/","name":"Tjekvik | Fallstudie Halliwell Jones","description":"Lesen Sie die Fallstudie von Halliwell Jones, um zu erfahren, wie die Einf\u00fchrung der digitalen Service-Kioske von Tjekvik die Wartezeit verk\u00fcrzt und die Produktivit\u00e4t des Autohauses erh\u00f6ht hat.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/tjekvik.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/#breadcrumblist"},"datePublished":"2025-03-07T14:21:55+00:00","dateModified":"2025-03-17T15:51:05+00:00"},{"@type":"WebSite","@id":"https:\/\/tjekvik.com\/de\/#website","url":"https:\/\/tjekvik.com\/de\/","name":"Tjekvik","description":"Self-Service Solutions for Dealerships","inLanguage":"de-DE","publisher":{"@id":"https:\/\/tjekvik.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Tjekvik | Self-Service Solutions for Dealerships","og:type":"article","og:title":"Tjekvik | Fallstudie Halliwell Jones","og:description":"Lesen Sie die Fallstudie von Halliwell Jones, um zu erfahren, wie die Einf\u00fchrung der digitalen Service-Kioske von Tjekvik die Wartezeit verk\u00fcrzt und die Produktivit\u00e4t des Autohauses erh\u00f6ht hat.","og:url":"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/","og:image":"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/02\/NK28037-Edit1-e1739453183974.jpg","og:image:secure_url":"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/02\/NK28037-Edit1-e1739453183974.jpg","og:image:width":1158,"og:image:height":1000,"article:published_time":"2025-03-07T14:21:55+00:00","article:modified_time":"2025-03-17T15:51:05+00:00","article:publisher":"https:\/\/www.facebook.com\/TjekvikAutoinnovationAps","twitter:card":"summary_large_image","twitter:title":"Tjekvik | Fallstudie Halliwell Jones","twitter:description":"Lesen Sie die Fallstudie von Halliwell Jones, um zu erfahren, wie die Einf\u00fchrung der digitalen Service-Kioske von Tjekvik die Wartezeit verk\u00fcrzt und die Produktivit\u00e4t des Autohauses erh\u00f6ht hat.","twitter:image":"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/02\/NK28037-Edit1-e1739453183974.jpg"},"aioseo_meta_data":{"post_id":"15225","title":null,"description":"Lesen Sie die Fallstudie von Halliwell Jones, um zu erfahren, wie die Einf\u00fchrung der digitalen Service-Kioske von Tjekvik die Wartezeit verk\u00fcrzt und die Produktivit\u00e4t des Autohauses erh\u00f6ht hat.","keywords":null,"keyphrases":{"focus":{"keyphrase":"Halliwell Jones","score":74,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[{"keyphrase":"digital service","score":53,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":null,"breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2025-03-12 12:50:57","updated":"2025-03-17 15:50:58","focus_keyword":"Halliwell Jones","additional_keywords":[{"word":"digital service","score":53}],"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\tTjekvik\n<\/span><span class=\"aioseo-breadcrumb-separator\">|<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/tjekvik.com\/de\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">|<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/tjekvik.com\/de\/kundenberichte\/\" title=\"Kundenberichte\">Kundenberichte<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">|<\/span><span class=\"aioseo-breadcrumb\">\n\tFallstudie Halliwell Jones\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Tjekvik","link":""},{"label":"Home","link":"https:\/\/tjekvik.com\/de\/"},{"label":"Kundenberichte","link":"https:\/\/tjekvik.com\/de\/kundenberichte\/"},{"label":"Fallstudie Halliwell Jones","link":"https:\/\/tjekvik.com\/de\/kundenberichte\/fallstudie-halliwell-jones\/"}],"_links":{"self":[{"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/pages\/15225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/comments?post=15225"}],"version-history":[{"count":2,"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/pages\/15225\/revisions"}],"predecessor-version":[{"id":15341,"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/pages\/15225\/revisions\/15341"}],"up":[{"embeddable":true,"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/pages\/3777"}],"wp:attachment":[{"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/media?parent=15225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}