{"id":16936,"date":"2025-01-12T11:57:58","date_gmt":"2025-01-12T11:57:58","guid":{"rendered":"https:\/\/tjekvik.com\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/"},"modified":"2025-07-06T04:51:34","modified_gmt":"2025-07-06T04:51:34","slug":"eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen","status":"publish","type":"post","link":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/","title":{"rendered":"Eine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen"},"content":{"rendered":"<ul>\n<li><em>Besonders gefragt sind Nachf\u00fcll\u00f6l (37 %), saisonale Fahrzeug-Checks (35 %) und Wartungspl\u00e4ne (30 %) <\/em><\/li>\n<li><em>Digitale Self-Service-L\u00f6sungen von Tjekvik pr\u00e4sentieren Zusatzprodukte und -dienstleistungen w\u00e4hrend des Online-Check-ins, um Konversionen und Gewinne zu maximieren<\/em><\/li>\n<li><em>Tjekvik digitale Selbstbedienungsl\u00f6sungen pr\u00e4sentieren Mehrwertprodukte und -dienstleistungen w\u00e4hrend des Online-Check-in-Prozesses, um Konversionen und Gewinne zu maximieren<\/em><\/li>\n<\/ul>\n<p>Eine \u00fcberw\u00e4ltigende Mehrheit der Kunden in Deutschland ist offen f\u00fcr Mehrwertprodukte und -dienstleistungen, wenn sie ihr Fahrzeug zur Wartung oder Reparatur bringen. Das ergab eine neue bundesweite Umfrage* im Auftrag von Tjekvik. Die Ergebnisse verdeutlichen die gro\u00dfe Chance f\u00fcr Autoh\u00e4user, ihre Ums\u00e4tze durch gut getimte Upselling-Prozesse zu steigern. <\/p>\n<p>Obwohl das allgemeine Interesse an Zusatzleistungen hoch ist, ergab die Umfrage von Tjekvik, dass fast die H\u00e4lfte (47 %) der Befragten es bevorzugt, au\u00dferhalb des Service-Empfangs \u00fcber diese Angebote informiert zu werden \u2013 beispielsweise beim Online-Check-in (33 %) oder an Self-Service-Terminals (14 %).<\/p>\n<p>Obwohl das Interesse der Kunden an Mehrwertdiensten gro\u00df ist, ergab die Umfrage von Tjekvik, dass fast die H\u00e4lfte (47%) der Befragten es vorziehen w\u00fcrden, von diesen zus\u00e4tzlichen Produkten und Dienstleistungen au\u00dferhalb der Service-Rezeption zu erfahren, z.B. beim Online-Check-in (33%) oder bei der Nutzung von Selbstbedienungskiosken (14%). Warteschlangen schrecken viele Menschen ab. 21% sind weniger bereit, Upselling-M\u00f6glichkeiten in Betracht zu ziehen, wenn sie auf lange Warteschlangen an der Service-Rezeption sto\u00dfen. <\/p>\n<p>Die gefragtesten Zusatzangebote sind:<br \/>&#8211; Nachf\u00fcll\u00f6l (37 %)<br \/>&#8211; Saisonale Fahrzeug-Checks, z. B. Winter- oder Sommer-Check (35 %)<br \/>&#8211; Wartungspl\u00e4ne (30 %)<br \/>&#8211; Klimaanlagen-Wartung (29 %)<br \/>&#8211; Scheibenwischerbl\u00e4tter (27 %)<br \/>&#8211; Garantieverl\u00e4ngerungen (25 %)<\/p>\n<p>\n\n<div class=\"hs-cta-embed hs-cta-simple-placeholder hs-cta-embed-108170456292\" data-hubspot-wrapper-cta-id=\"108170456292\"><a href=\"https:\/\/cta-eu1.hubspot.com\/web-interactives\/public\/v1\/track\/redirect?encryptedPayload=AVxigLJ48eFSeC5iyPw%2FYJQeZZ%2B2y%2Fb5GjjBAn%2BcbCwiLWLFFS4x1jMEqzN9O8nPDdumC8M62hUt3qdw4gfg0dBRe5AZM41did0fS%2F1B4YxfxC7VvkE%3D&#038;webInteractiveContentId=108170456292&#038;portalId=26682254\" target=\"_blank\" rel=\"noopener\"> <img decoding=\"async\" src=\"https:\/\/hubspot-no-cache-eu1-prod.s3.amazonaws.com\/cta\/default\/26682254\/interactive-108170456292.png\" alt=\"Beginnen Sie Ihre digitale Reise Sprechen Sie mit uns, um Ihren Bedarf zu ermitteln und die perfekte Selbstbedienungsl\u00f6sung zu finden.   \"\/> <\/a><\/div>\n<p><\/p><\/p>\n<p>Christian Mark, CEO und Mitbegr\u00fcnder von Tjekvik, sagte: &#8222;Unsere Ergebnisse zeigen, dass Autoh\u00e4user eine hervorragende M\u00f6glichkeit haben, ihren Umsatz zu steigern, indem sie ihren Ansatz f\u00fcr das Upselling anpassen. Digitale und Selbstbedienungsoptionen bieten den Kunden eine pers\u00f6nlichere und weniger bedr\u00e4ngte Interaktion, was wiederum den Umsatz der Autoh\u00e4user erh\u00f6ht.&#8220;<\/p>\n<p>Die Aftersales-Self-Service-Check-in-L\u00f6sungen von Tjekvik f\u00fcr zuhause und den Innenbereich erm\u00f6glichen es Kunden, ihr Fahrzeug sicher ein- und auszuchecken \u2013 wann, wo und wie sie m\u00f6chten. Ob bequem von zu Hause aus auf dem eigenen Ger\u00e4t oder direkt im Autohaus an benutzerfreundlichen Touchscreen-Terminals. Die Outdoor-Terminals von Tjekvik bieten dar\u00fcber hinaus einen nahtlosen 24\/7-Check-in- und Check-out-Service. <\/p>\n<p>Um den Umsatz zu steigern, k\u00f6nnen diese L\u00f6sungen auch genutzt werden, um Kunden w\u00e4hrend des Check-ins auf klare und konsistente Weise optionale Zusatzprodukte und -dienstleistungen zu pr\u00e4sentieren \u2013 eine Aufgabe, f\u00fcr die Serviceberater oft nicht genug Zeit oder Schulung haben.<\/p>\n<p>*Die Studie wurde von OnePoll durchgef\u00fchrt; befragt wurden 1.000 Autobesitzer in Deutschland.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Besonders gefragt sind Nachf\u00fcll\u00f6l (37 %), saisonale Fahrzeug-Checks (35 %) und Wartungspl\u00e4ne (30 %) Digitale Self-Service-L\u00f6sungen von Tjekvik pr\u00e4sentieren Zusatzprodukte und -dienstleistungen w\u00e4hrend des Online-Check-ins, um Konversionen und Gewinne zu maximieren Tjekvik digitale Selbstbedienungsl\u00f6sungen pr\u00e4sentieren Mehrwertprodukte und -dienstleistungen w\u00e4hrend des Online-Check-in-Prozesses, um Konversionen und Gewinne zu maximieren Eine \u00fcberw\u00e4ltigende Mehrheit der Kunden in Deutschland ist [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":16931,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[59],"tags":[],"class_list":["post-16936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Besonders gefragt sind Nachf\u00fcll\u00f6l (37 %), saisonale Fahrzeug-Checks (35 %) und Wartungspl\u00e4ne (30 %) Digitale Self-Service-L\u00f6sungen von Tjekvik pr\u00e4sentieren Zusatzprodukte und -dienstleistungen w\u00e4hrend des Online-Check-ins, um Konversionen und Gewinne zu maximieren Tjekvik digitale Selbstbedienungsl\u00f6sungen pr\u00e4sentieren Mehrwertprodukte und -dienstleistungen w\u00e4hrend des Online-Check-in-Prozesses, um Konversionen und Gewinne zu maximieren Eine \u00fcberw\u00e4ltigende Mehrheit der Kunden in Deutschland ist\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"Ana Dragnea\"\/>\n\t<meta name=\"google-site-verification\" content=\"9PXm2QtMM5RDVYRpa-EGrnVOmNWMB8RJJfHjriN0nJQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Tjekvik | Self-Service Solutions for Dealerships\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Tjekvik | Eine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen\" \/>\n\t\t<meta property=\"og:description\" content=\"Besonders gefragt sind Nachf\u00fcll\u00f6l (37 %), saisonale Fahrzeug-Checks (35 %) und Wartungspl\u00e4ne (30 %) Digitale Self-Service-L\u00f6sungen von Tjekvik pr\u00e4sentieren Zusatzprodukte und -dienstleistungen w\u00e4hrend des Online-Check-ins, um Konversionen und Gewinne zu maximieren Tjekvik digitale Selbstbedienungsl\u00f6sungen pr\u00e4sentieren Mehrwertprodukte und -dienstleistungen w\u00e4hrend des Online-Check-in-Prozesses, um Konversionen und Gewinne zu maximieren Eine \u00fcberw\u00e4ltigende Mehrheit der Kunden in Deutschland ist\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/05\/blog-cover.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/05\/blog-cover.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1640\" \/>\n\t\t<meta property=\"og:image:height\" content=\"924\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-01-12T11:57:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-07-06T04:51:34+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TjekvikAutoinnovationAps\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Tjekvik | Eine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Besonders gefragt sind Nachf\u00fcll\u00f6l (37 %), saisonale Fahrzeug-Checks (35 %) und Wartungspl\u00e4ne (30 %) Digitale Self-Service-L\u00f6sungen von Tjekvik pr\u00e4sentieren Zusatzprodukte und -dienstleistungen w\u00e4hrend des Online-Check-ins, um Konversionen und Gewinne zu maximieren Tjekvik digitale Selbstbedienungsl\u00f6sungen pr\u00e4sentieren Mehrwertprodukte und -dienstleistungen w\u00e4hrend des Online-Check-in-Prozesses, um Konversionen und Gewinne zu maximieren Eine \u00fcberw\u00e4ltigende Mehrheit der Kunden in Deutschland ist\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/05\/blog-cover.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/#blogposting\",\"name\":\"Tjekvik | Eine landesweite Umfrage zeigt: Fast die H\\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\\u00dferhalb des Service-Empfangs in Betracht zu ziehen\",\"headline\":\"Eine landesweite Umfrage zeigt: Fast die H\\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\\u00dferhalb des Service-Empfangs in Betracht zu ziehen\",\"author\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/author\\\/agtj448sjl\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/tjekvik.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/blog-cover.webp\",\"width\":1640,\"height\":924},\"datePublished\":\"2025-01-12T11:57:58+00:00\",\"dateModified\":\"2025-07-06T04:51:34+00:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/#webpage\"},\"articleSection\":\"Nachrichten, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/#listItem\",\"position\":2,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/category\\\/nachrichten\\\/#listItem\",\"name\":\"Nachrichten\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"#listItem\",\"name\":\"Tjekvik\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/category\\\/nachrichten\\\/#listItem\",\"position\":3,\"name\":\"Nachrichten\",\"item\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/category\\\/nachrichten\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/#listItem\",\"name\":\"Eine landesweite Umfrage zeigt: Fast die H\\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\\u00dferhalb des Service-Empfangs in Betracht zu ziehen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/#listItem\",\"position\":4,\"name\":\"Eine landesweite Umfrage zeigt: Fast die H\\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\\u00dferhalb des Service-Empfangs in Betracht zu ziehen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/category\\\/nachrichten\\\/#listItem\",\"name\":\"Nachrichten\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/#organization\",\"name\":\"Tjekvik\",\"description\":\"Self-Service Solutions for Dealerships\",\"url\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/\",\"telephone\":\"+447470214847\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/tjekvik.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/TJEKVIK_Brandmark_RGB.png\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/#organizationLogo\",\"width\":473,\"height\":473,\"caption\":\"Tjekvik brand icon\"},\"image\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/@tjekvik\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tjekvik\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/author\\\/agtj448sjl\\\/#author\",\"url\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/author\\\/agtj448sjl\\\/\",\"name\":\"Ana Dragnea\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/566e45fbbe41556202200f5bc526a882858a8c0804bd53df74885bb7b9b271c1?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ana Dragnea\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/#webpage\",\"url\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/\",\"name\":\"Tjekvik | Eine landesweite Umfrage zeigt: Fast die H\\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\\u00dferhalb des Service-Empfangs in Betracht zu ziehen\",\"description\":\"Besonders gefragt sind Nachf\\u00fcll\\u00f6l (37 %), saisonale Fahrzeug-Checks (35 %) und Wartungspl\\u00e4ne (30 %) Digitale Self-Service-L\\u00f6sungen von Tjekvik pr\\u00e4sentieren Zusatzprodukte und -dienstleistungen w\\u00e4hrend des Online-Check-ins, um Konversionen und Gewinne zu maximieren Tjekvik digitale Selbstbedienungsl\\u00f6sungen pr\\u00e4sentieren Mehrwertprodukte und -dienstleistungen w\\u00e4hrend des Online-Check-in-Prozesses, um Konversionen und Gewinne zu maximieren Eine \\u00fcberw\\u00e4ltigende Mehrheit der Kunden in Deutschland ist\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/author\\\/agtj448sjl\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/author\\\/agtj448sjl\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/tjekvik.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/blog-cover.webp\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/#mainImage\",\"width\":1640,\"height\":924},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/blog\\\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\\\/#mainImage\"},\"datePublished\":\"2025-01-12T11:57:58+00:00\",\"dateModified\":\"2025-07-06T04:51:34+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/\",\"name\":\"Tjekvik\",\"description\":\"Self-Service Solutions for Dealerships\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/tjekvik.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Tjekvik | Eine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen<\/title>\n\n","aioseo_head_json":{"title":"Tjekvik | Eine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen","description":"Besonders gefragt sind Nachf\u00fcll\u00f6l (37 %), saisonale Fahrzeug-Checks (35 %) und Wartungspl\u00e4ne (30 %) Digitale Self-Service-L\u00f6sungen von Tjekvik pr\u00e4sentieren Zusatzprodukte und -dienstleistungen w\u00e4hrend des Online-Check-ins, um Konversionen und Gewinne zu maximieren Tjekvik digitale Selbstbedienungsl\u00f6sungen pr\u00e4sentieren Mehrwertprodukte und -dienstleistungen w\u00e4hrend des Online-Check-in-Prozesses, um Konversionen und Gewinne zu maximieren Eine \u00fcberw\u00e4ltigende Mehrheit der Kunden in Deutschland ist","canonical_url":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"google-site-verification":"9PXm2QtMM5RDVYRpa-EGrnVOmNWMB8RJJfHjriN0nJQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/#blogposting","name":"Tjekvik | Eine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen","headline":"Eine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen","author":{"@id":"https:\/\/tjekvik.com\/de\/blog\/author\/agtj448sjl\/#author"},"publisher":{"@id":"https:\/\/tjekvik.com\/de\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/05\/blog-cover.webp","width":1640,"height":924},"datePublished":"2025-01-12T11:57:58+00:00","dateModified":"2025-07-06T04:51:34+00:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/#webpage"},"isPartOf":{"@id":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/#webpage"},"articleSection":"Nachrichten, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/#listItem","position":2,"name":"Home","item":"https:\/\/tjekvik.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/blog\/category\/nachrichten\/#listItem","name":"Nachrichten"},"previousItem":{"@type":"ListItem","@id":"#listItem","name":"Tjekvik"}},{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/blog\/category\/nachrichten\/#listItem","position":3,"name":"Nachrichten","item":"https:\/\/tjekvik.com\/de\/blog\/category\/nachrichten\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/#listItem","name":"Eine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/#listItem","position":4,"name":"Eine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen","previousItem":{"@type":"ListItem","@id":"https:\/\/tjekvik.com\/de\/blog\/category\/nachrichten\/#listItem","name":"Nachrichten"}}]},{"@type":"Organization","@id":"https:\/\/tjekvik.com\/de\/#organization","name":"Tjekvik","description":"Self-Service Solutions for Dealerships","url":"https:\/\/tjekvik.com\/de\/","telephone":"+447470214847","logo":{"@type":"ImageObject","url":"https:\/\/tjekvik.com\/wp-content\/uploads\/2023\/05\/TJEKVIK_Brandmark_RGB.png","@id":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/#organizationLogo","width":473,"height":473,"caption":"Tjekvik brand icon"},"image":{"@id":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/#organizationLogo"},"sameAs":["https:\/\/www.youtube.com\/@tjekvik","https:\/\/www.linkedin.com\/company\/tjekvik\/"]},{"@type":"Person","@id":"https:\/\/tjekvik.com\/de\/blog\/author\/agtj448sjl\/#author","url":"https:\/\/tjekvik.com\/de\/blog\/author\/agtj448sjl\/","name":"Ana Dragnea","image":{"@type":"ImageObject","@id":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/566e45fbbe41556202200f5bc526a882858a8c0804bd53df74885bb7b9b271c1?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ana Dragnea"}},{"@type":"WebPage","@id":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/#webpage","url":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/","name":"Tjekvik | Eine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen","description":"Besonders gefragt sind Nachf\u00fcll\u00f6l (37 %), saisonale Fahrzeug-Checks (35 %) und Wartungspl\u00e4ne (30 %) Digitale Self-Service-L\u00f6sungen von Tjekvik pr\u00e4sentieren Zusatzprodukte und -dienstleistungen w\u00e4hrend des Online-Check-ins, um Konversionen und Gewinne zu maximieren Tjekvik digitale Selbstbedienungsl\u00f6sungen pr\u00e4sentieren Mehrwertprodukte und -dienstleistungen w\u00e4hrend des Online-Check-in-Prozesses, um Konversionen und Gewinne zu maximieren Eine \u00fcberw\u00e4ltigende Mehrheit der Kunden in Deutschland ist","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/tjekvik.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/#breadcrumblist"},"author":{"@id":"https:\/\/tjekvik.com\/de\/blog\/author\/agtj448sjl\/#author"},"creator":{"@id":"https:\/\/tjekvik.com\/de\/blog\/author\/agtj448sjl\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/05\/blog-cover.webp","@id":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/#mainImage","width":1640,"height":924},"primaryImageOfPage":{"@id":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/#mainImage"},"datePublished":"2025-01-12T11:57:58+00:00","dateModified":"2025-07-06T04:51:34+00:00"},{"@type":"WebSite","@id":"https:\/\/tjekvik.com\/de\/#website","url":"https:\/\/tjekvik.com\/de\/","name":"Tjekvik","description":"Self-Service Solutions for Dealerships","inLanguage":"de-DE","publisher":{"@id":"https:\/\/tjekvik.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Tjekvik | Self-Service Solutions for Dealerships","og:type":"article","og:title":"Tjekvik | Eine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen","og:description":"Besonders gefragt sind Nachf\u00fcll\u00f6l (37 %), saisonale Fahrzeug-Checks (35 %) und Wartungspl\u00e4ne (30 %) Digitale Self-Service-L\u00f6sungen von Tjekvik pr\u00e4sentieren Zusatzprodukte und -dienstleistungen w\u00e4hrend des Online-Check-ins, um Konversionen und Gewinne zu maximieren Tjekvik digitale Selbstbedienungsl\u00f6sungen pr\u00e4sentieren Mehrwertprodukte und -dienstleistungen w\u00e4hrend des Online-Check-in-Prozesses, um Konversionen und Gewinne zu maximieren Eine \u00fcberw\u00e4ltigende Mehrheit der Kunden in Deutschland ist","og:url":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/","og:image":"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/05\/blog-cover.webp","og:image:secure_url":"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/05\/blog-cover.webp","og:image:width":1640,"og:image:height":924,"article:published_time":"2025-01-12T11:57:58+00:00","article:modified_time":"2025-07-06T04:51:34+00:00","article:publisher":"https:\/\/www.facebook.com\/TjekvikAutoinnovationAps","twitter:card":"summary_large_image","twitter:title":"Tjekvik | Eine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen","twitter:description":"Besonders gefragt sind Nachf\u00fcll\u00f6l (37 %), saisonale Fahrzeug-Checks (35 %) und Wartungspl\u00e4ne (30 %) Digitale Self-Service-L\u00f6sungen von Tjekvik pr\u00e4sentieren Zusatzprodukte und -dienstleistungen w\u00e4hrend des Online-Check-ins, um Konversionen und Gewinne zu maximieren Tjekvik digitale Selbstbedienungsl\u00f6sungen pr\u00e4sentieren Mehrwertprodukte und -dienstleistungen w\u00e4hrend des Online-Check-in-Prozesses, um Konversionen und Gewinne zu maximieren Eine \u00fcberw\u00e4ltigende Mehrheit der Kunden in Deutschland ist","twitter:image":"https:\/\/tjekvik.com\/wp-content\/uploads\/2025\/05\/blog-cover.webp"},"aioseo_meta_data":{"post_id":"16936","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-19 08:39:48","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2025-05-01 12:11:07","updated":"2026-05-19 08:39:48"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\tTjekvik\n<\/span><span class=\"aioseo-breadcrumb-separator\">|<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/tjekvik.com\/de\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">|<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/tjekvik.com\/de\/blog\/category\/nachrichten\/\" title=\"Nachrichten\">Nachrichten<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">|<\/span><span class=\"aioseo-breadcrumb\">\n\tEine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Tjekvik","link":""},{"label":"Home","link":"https:\/\/tjekvik.com\/de\/"},{"label":"Nachrichten","link":"https:\/\/tjekvik.com\/de\/blog\/category\/nachrichten\/"},{"label":"Eine landesweite Umfrage zeigt: Fast die H\u00e4lfte der Aftersales-Kunden (47 %) zieht es vor, Zusatzangebote au\u00dferhalb des Service-Empfangs in Betracht zu ziehen","link":"https:\/\/tjekvik.com\/de\/blog\/eine-landesweite-umfrage-zeigt-fast-die-haelfte-der-aftersales-kunden-47-zieht-es-vor-zusatzangebote-ausserhalb-des-service-empfangs-in-betracht-zu-ziehen\/"}],"_links":{"self":[{"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/posts\/16936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/comments?post=16936"}],"version-history":[{"count":4,"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/posts\/16936\/revisions"}],"predecessor-version":[{"id":17086,"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/posts\/16936\/revisions\/17086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/media\/16931"}],"wp:attachment":[{"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/media?parent=16936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/categories?post=16936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tjekvik.com\/de\/wp-json\/wp\/v2\/tags?post=16936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}